{"id":12161,"date":"2022-09-16T10:22:30","date_gmt":"2022-09-16T09:22:30","guid":{"rendered":"https:\/\/www.repscan.com\/?p=12161"},"modified":"2024-12-17T16:52:21","modified_gmt":"2024-12-17T15:52:21","slug":"que-es-ampliacion-capital","status":"publish","type":"post","link":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/","title":{"rendered":"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace?"},"content":{"rendered":"\n<p>En este art\u00edculo te explicamos lo que es una ampliaci\u00f3n de capital, los pasos que tienes que dar para llevarla a cabo y su fiscalidad.<\/p>\n\n\n\n<!--more-->\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es una ampliaci\u00f3n de capital?<\/strong><\/h2>\n\n\n\n<p><strong>Una ampliaci\u00f3n de capital es una operaci\u00f3n financiera que lleva a cabo una empresa para incrementar sus recursos propios<\/strong> con el prop\u00f3sito de llevar a cabo nuevas inversiones o por diferentes necesidades de financiaci\u00f3n.<\/p>\n\n\n\n<p>B\u00e1sicamente con una ampliaci\u00f3n de capital se amplia el capital social de una empresa.<strong> El capital social ser\u00edan los bienes que tienen los accionistas dentro de una empresa<\/strong> y que pueden utilizar para llevar a cabo inversiones sin derecho a devoluci\u00f3n. Por poner un ejemplo, se llevan a cabo aportaciones de capital para que la empresa inicie y desarrolle el negocio.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo afecta una ampliaci\u00f3n de capital a los accionistas?<\/strong><\/h2>\n\n\n\n<p>Una ampliaci\u00f3n de capital afecta directamente a los accionistas de la empresa, ya que estos <strong>pueden ver disminuido su porcentaje de participaci\u00f3n debido a que ahora hay una mayor cantidad de acciones dentro de la empresa. <\/strong>Por este motivo, los socios antiguos suelen contar con un <strong>derecho de suscripci\u00f3n preferente que les da ventaja sobre los nuevos socios.<\/strong><\/p>\n\n\n\n<p>Este derecho de suscripci\u00f3n preferente lo pueden utilizar para comprar nuevas acciones de la empresa o, si lo prefieren, pueden venderlo para que sean otros accionistas los que las compren. A la hora de llevar a cabo la compra de nuevas acciones el precio puede ser a la par, si es el mismo que el anterior, por encima de la par si es superior o liberada, una opci\u00f3n que puede ser completamente gratuita para los accionistas.\u00a0<\/p>\n\n\n\n<p>Es importante recordar que una ampliaci\u00f3n de capital<strong> diluye el valor de los t\u00edtulos. <\/strong>Esto se debe a que, cuando se emiten m\u00e1s acciones, el valor de cada una de estas bajar\u00e1 debido a que el valor total de la compa\u00f1\u00eda se reparte entre un mayor n\u00famero de acciones.\u00a0 Para evitar que esto ocurra se puede recurrir a la prima de emisi\u00f3n, una compensaci\u00f3n a trav\u00e9s de la cual los nuevos accionistas estar\u00e1n tambi\u00e9n pagando por las reservas de la empresa.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQui\u00e9n decide una ampliaci\u00f3n de capital?<\/strong><\/h2>\n\n\n\n<p>Llevar a cabo una ampliaci\u00f3n de capital es una operaci\u00f3n de suma importancia para la empresa. Por este motivo, <strong>es el consejo de administraci\u00f3n de la empresa quien propone la ampliaci\u00f3n de capital a los accionistas por norma general.&nbsp;<\/strong><\/p>\n\n\n\n<p>Por otro lado, la ley estipula que <strong>cualquier accionista que posea m\u00e1s de un 5% de la propiedad puede pedir que se convoque una junta<\/strong> y plantear sus propias alternativas de proyecto entre las cuales, por supuesto, se encuentra la ampliaci\u00f3n del capital.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1ndo es conveniente incrementar el capital de la empresa?<\/strong><\/h2>\n\n\n\n<p>Son muchos los motivos por los cuales llevar a cabo un incremento de capital por parte de la empresa es una buena idea. El principal motivo es cuando la empresa necesita capital, esto puede deberse a que quiere llevar a cabo una inversi\u00f3n importante, necesita financiar un nuevo proyecto o no puede financiarse a trav\u00e9s de una entidad de cr\u00e9dito.<\/p>\n\n\n\n<p>As\u00ed mismo, tambi\u00e9n es conveniente llevar a cabo una ampliaci\u00f3n de capital cuando se producen p\u00e9rdidas que<strong> dejan reducido el patrimonio neto de la empresa en una cantidad inferior del capital social.<\/strong> Tambi\u00e9n es conveniente hacer esta ampliaci\u00f3n si hay una reducci\u00f3n del capital social por debajo del m\u00ednimo legal para seguir cumpliendo con la ley.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo se hace una ampliaci\u00f3n de capital?<\/strong><\/h2>\n\n\n\n<p>Para entender mejor como se hace una ampliaci\u00f3n de capital vamos a mostrar los pasos necesarios para hacerla.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Propuesta de ampliaci\u00f3n de capital.<\/strong> La propuesta ser\u00e1 llevada a cabo por el consejo de administraci\u00f3n o por cualquier accionista que tenga m\u00e1s de un 5% de la sociedad, como hemos visto. Esta propuesta deber\u00e1 de contar con un informe que explique en qu\u00e9 consiste y c\u00f3mo se va a llevar a cabo.<\/li>\n\n\n\n<li><strong>Acuerdo en la junta.<\/strong> Se convocar\u00e1 una Junta General para aprobar la propuesta. Esta propuesta deber\u00e1 de figurar en el orden del d\u00eda junto a todas las caracter\u00edsticas necesarias. Ser\u00e1 necesario contar con mayor\u00eda como establece la <a data-type=\"URL\" data-id=\"https:\/\/www.repscan.com\/es\/blog\/ley-sociedades-capital\/\" href=\"https:\/\/www.repscan.com\/es\/blog\/ley-sociedades-capital\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ley de Sociedades de Capital<\/a> para que la propuesta salga adelante.<\/li>\n\n\n\n<li><strong>Ejecuci\u00f3n. <\/strong>En este paso se llevar\u00e1n a cabo las aportaciones de los socios nuevos o de los antiguos, dependiendo de las condiciones que se hayan aprobado en la Junta General.<\/li>\n\n\n\n<li><strong>Escritura p\u00fablica. <\/strong>En este paso el acuerdo deber\u00e1 de plasmarse a trav\u00e9s de una escritura p\u00fablica mediante Notario. En esta escritura se contemplar\u00e1 todo el contenido del acta de la Junta General, as\u00ed como la composici\u00f3n y distribuci\u00f3n del capital social.<\/li>\n\n\n\n<li><strong>Registro Mercantil.<\/strong> El \u00faltimo paso es inscribir la escritura en el Registro Mercantil para que esta sea p\u00fablica.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ventajas e inconvenientes de una ampliaci\u00f3n de capital<\/strong><\/h2>\n\n\n\n<p>Llevar a cabo una ampliaci\u00f3n de capital tiene sus beneficios, pero tambi\u00e9n <strong>implica asumir alg\u00fan que otro riesgo.<\/strong><\/p>\n\n\n\n<p>Una ampliaci\u00f3n de capital tiene como ventaja que <strong>hace m\u00e1s fuerte a la empresa, especialmente a los clientes, a los proveedores y a los futuros inversores. <\/strong>Por otro lado, te permite tambi\u00e9n llevar a cabo mayores inversiones y es una forma de financiarse de forma interna sin tener que depender de los bancos.<\/p>\n\n\n\n<p>Por otro lado, debes de considerar que una ampliaci\u00f3n de capital <strong>suele provocar el llamado efecto diluci\u00f3n.<\/strong> Este efecto consiste en que las acciones se emiten a precios m\u00e1s bajos de lo que estaban en el mercado, produciendo una ampliaci\u00f3n de capital para echar a un socio si el porcentaje de participaci\u00f3n de este queda reducido a m\u00ednimos.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 impuestos se pagan por una ampliaci\u00f3n de capital?<\/strong><\/h2>\n\n\n\n<p>Las ampliaciones de capital <strong>se encuentran exentas de tributaci\u00f3n por parte de las operaciones societarias.<\/strong> El \u00fanico momento en el que se deber\u00e1 de hacer cuentas con Hacienda<strong> ser\u00e1 cuando se vendan las acciones<\/strong>, por lo que habr\u00e1 que calcular la plusval\u00eda generada en el momento que hubo la ampliaci\u00f3n de capital. Mientras ese momento no llegue no tendr\u00e1s que tributar en ning\u00fan momento debido a la ampliaci\u00f3n de capital.\u00a0<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3317\" class=\"elementor elementor-3317\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-c26d2b3 elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"c26d2b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc9a6b8\" data-id=\"bc9a6b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-635edc3 elementor-widget elementor-widget-spacer\" data-id=\"635edc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b75782d elementor-widget elementor-widget-heading\" data-id=\"b75782d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-small\">\u00bfTienes contenido negativo afectando tu reputaci\u00f3n online?<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc9cd1 elementor-widget elementor-widget-text-editor\" data-id=\"5dc9cd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" data-start=\"203\" data-end=\"319\">Fotos, v\u00eddeos, rese\u00f1as negativas o noticias falsas pueden da\u00f1ar tu imagen. <strong>Te ayudamos a eliminarlos o desindexarlos.<\/strong> <strong data-start=\"271\" data-end=\"317\">D\u00e9janos tus datos y te contactamos.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8efc46c elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"8efc46c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe aria-label='ESP_ZOHO_FORM_BLOG' frameborder=\"0\" style=\"height:1100px;width:99%;border:none;\" src='https:\/\/forms.zohopublic.eu\/repscan\/form\/ESPZOHOFORMBLOG\/formperma\/fNklprMD581Qphnz_99HoDaem83UEE5xWdMM0Kk9Hmk'><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-779c95e elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"779c95e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-346e4c9\" data-id=\"346e4c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f38e866 elementor-widget elementor-widget-heading\" data-id=\"f38e866\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-small\">\u00bfTienes contenido negativo afectando tu reputaci\u00f3n online?<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dc1214 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2dc1214\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03d0b84 elementor-widget elementor-widget-text-editor\" data-id=\"03d0b84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" data-start=\"203\" data-end=\"319\">Fotos, v\u00eddeos, rese\u00f1as negativas o noticias falsas pueden da\u00f1ar tu imagen. <strong>Te ayudamos a eliminarlos o desindexarlos.<\/strong> <strong data-start=\"271\" data-end=\"317\">D\u00e9janos tus datos y te contactamos.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c80e7b elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"9c80e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe aria-label='ESP_ZOHO_FORM_BLOG' frameborder=\"0\" style=\"height:1205px;width:99%;border:none;\" src='https:\/\/forms.zohopublic.eu\/repscan\/form\/ESPZOHOFORMBLOG\/formperma\/fNklprMD581Qphnz_99HoDaem83UEE5xWdMM0Kk9Hmk'><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":12163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[123,70],"tags":[134],"class_list":["post-12161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enciclopedia","category-legal","tag-articulos","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace? | RepScan<\/title>\n<meta name=\"description\" content=\"Descubre qu\u00e9 es una ampliaci\u00f3n de capital, c\u00f3mo se realiza y qu\u00e9 beneficios aporta a las empresas en este blog.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace? | RepScan\" \/>\n<meta property=\"og:description\" content=\"Descubre qu\u00e9 es una ampliaci\u00f3n de capital, c\u00f3mo se realiza y qu\u00e9 beneficios aporta a las empresas en este blog.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/\" \/>\n<meta property=\"og:site_name\" content=\"RepScan\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/josep.collrodriguez\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-16T09:22:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-17T15:52:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repscan.com\/wp-content\/uploads\/2022\/09\/ampliacion-de-capital-23r4-e1741853787747.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Josep Coll\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jcollrodriguez\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Josep Coll\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/\"},\"author\":{\"name\":\"Josep Coll\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#\\\/schema\\\/person\\\/90ce98e40942db5cd81931ae6d4f5930\"},\"headline\":\"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace?\",\"datePublished\":\"2022-09-16T09:22:30+00:00\",\"dateModified\":\"2024-12-17T15:52:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/\"},\"wordCount\":1092,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/ampliacion-de-capital-23r4-e1741853787747.jpg\",\"keywords\":[\"Art\u00edculos\"],\"articleSection\":[\"Enciclopedia\",\"Legal\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/\",\"name\":\"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace? | RepScan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/ampliacion-de-capital-23r4-e1741853787747.jpg\",\"datePublished\":\"2022-09-16T09:22:30+00:00\",\"dateModified\":\"2024-12-17T15:52:21+00:00\",\"description\":\"Descubre qu\u00e9 es una ampliaci\u00f3n de capital, c\u00f3mo se realiza y qu\u00e9 beneficios aporta a las empresas en este blog.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/ampliacion-de-capital-23r4-e1741853787747.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/ampliacion-de-capital-23r4-e1741853787747.jpg\",\"width\":1000,\"height\":563,\"caption\":\"que es una ampliacion de capital, hombres de negocio en una reunion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/que-es-ampliacion-capital\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/\",\"name\":\"RepScan\",\"description\":\"Plataforma de Reputaci\u00f3n Digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#organization\",\"name\":\"RepScan\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/repscan_header_HQ.png\",\"contentUrl\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/repscan_header_HQ.png\",\"width\":550,\"height\":130,\"caption\":\"RepScan\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#\\\/schema\\\/person\\\/90ce98e40942db5cd81931ae6d4f5930\",\"name\":\"Josep Coll\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a80166fc6fb143ca540f44cf002abf806e5dde081f97b15553e80bb53ad1e91d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a80166fc6fb143ca540f44cf002abf806e5dde081f97b15553e80bb53ad1e91d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a80166fc6fb143ca540f44cf002abf806e5dde081f97b15553e80bb53ad1e91d?s=96&d=mm&r=g\",\"caption\":\"Josep Coll\"},\"description\":\"Abogado con m\u00e1s de 20 a\u00f1os de ejercicio y m\u00e1s de 10 combatiendo la pirater\u00eda en Internet y mejorando la reputaci\u00f3n online de empresas y personas. Co-Fundador de RepScan y m\u00fasico a tiempo completo.\",\"sameAs\":[\"https:\\\/\\\/josepcoll.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/josep.collrodriguez\",\"https:\\\/\\\/x.com\\\/jcollrodriguez\"],\"url\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/author\\\/jcoll\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace? | RepScan","description":"Descubre qu\u00e9 es una ampliaci\u00f3n de capital, c\u00f3mo se realiza y qu\u00e9 beneficios aporta a las empresas en este blog.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace? | RepScan","og_description":"Descubre qu\u00e9 es una ampliaci\u00f3n de capital, c\u00f3mo se realiza y qu\u00e9 beneficios aporta a las empresas en este blog.","og_url":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/","og_site_name":"RepScan","article_author":"https:\/\/www.facebook.com\/josep.collrodriguez","article_published_time":"2022-09-16T09:22:30+00:00","article_modified_time":"2024-12-17T15:52:21+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/www.repscan.com\/wp-content\/uploads\/2022\/09\/ampliacion-de-capital-23r4-e1741853787747.jpg","type":"image\/jpeg"}],"author":"Josep Coll","twitter_card":"summary_large_image","twitter_creator":"@jcollrodriguez","twitter_misc":{"Escrito por":"Josep Coll","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/#article","isPartOf":{"@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/"},"author":{"name":"Josep Coll","@id":"https:\/\/www.repscan.com\/es\/#\/schema\/person\/90ce98e40942db5cd81931ae6d4f5930"},"headline":"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace?","datePublished":"2022-09-16T09:22:30+00:00","dateModified":"2024-12-17T15:52:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/"},"wordCount":1092,"commentCount":2,"publisher":{"@id":"https:\/\/www.repscan.com\/es\/#organization"},"image":{"@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repscan.com\/wp-content\/uploads\/2022\/09\/ampliacion-de-capital-23r4-e1741853787747.jpg","keywords":["Art\u00edculos"],"articleSection":["Enciclopedia","Legal"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/","url":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/","name":"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace? | RepScan","isPartOf":{"@id":"https:\/\/www.repscan.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/#primaryimage"},"image":{"@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repscan.com\/wp-content\/uploads\/2022\/09\/ampliacion-de-capital-23r4-e1741853787747.jpg","datePublished":"2022-09-16T09:22:30+00:00","dateModified":"2024-12-17T15:52:21+00:00","description":"Descubre qu\u00e9 es una ampliaci\u00f3n de capital, c\u00f3mo se realiza y qu\u00e9 beneficios aporta a las empresas en este blog.","breadcrumb":{"@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/#primaryimage","url":"https:\/\/www.repscan.com\/wp-content\/uploads\/2022\/09\/ampliacion-de-capital-23r4-e1741853787747.jpg","contentUrl":"https:\/\/www.repscan.com\/wp-content\/uploads\/2022\/09\/ampliacion-de-capital-23r4-e1741853787747.jpg","width":1000,"height":563,"caption":"que es una ampliacion de capital, hombres de negocio en una reunion"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repscan.com\/es\/blog\/que-es-ampliacion-capital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.repscan.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es una ampliaci\u00f3n de capital y c\u00f3mo se hace?"}]},{"@type":"WebSite","@id":"https:\/\/www.repscan.com\/es\/#website","url":"https:\/\/www.repscan.com\/es\/","name":"RepScan","description":"Plataforma de Reputaci\u00f3n Digital","publisher":{"@id":"https:\/\/www.repscan.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repscan.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repscan.com\/es\/#organization","name":"RepScan","url":"https:\/\/www.repscan.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repscan.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/07\/repscan_header_HQ.png","contentUrl":"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/07\/repscan_header_HQ.png","width":550,"height":130,"caption":"RepScan"},"image":{"@id":"https:\/\/www.repscan.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repscan.com\/es\/#\/schema\/person\/90ce98e40942db5cd81931ae6d4f5930","name":"Josep Coll","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a80166fc6fb143ca540f44cf002abf806e5dde081f97b15553e80bb53ad1e91d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a80166fc6fb143ca540f44cf002abf806e5dde081f97b15553e80bb53ad1e91d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a80166fc6fb143ca540f44cf002abf806e5dde081f97b15553e80bb53ad1e91d?s=96&d=mm&r=g","caption":"Josep Coll"},"description":"Abogado con m\u00e1s de 20 a\u00f1os de ejercicio y m\u00e1s de 10 combatiendo la pirater\u00eda en Internet y mejorando la reputaci\u00f3n online de empresas y personas. Co-Fundador de RepScan y m\u00fasico a tiempo completo.","sameAs":["https:\/\/josepcoll.com\/","https:\/\/www.facebook.com\/josep.collrodriguez","https:\/\/x.com\/jcollrodriguez"],"url":"https:\/\/www.repscan.com\/es\/blog\/author\/jcoll\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/posts\/12161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/comments?post=12161"}],"version-history":[{"count":0,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/posts\/12161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/media\/12163"}],"wp:attachment":[{"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/media?parent=12161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/categories?post=12161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/tags?post=12161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}