{"id":1191,"date":"2021-08-11T19:15:00","date_gmt":"2021-08-11T18:15:00","guid":{"rendered":"https:\/\/www.repscan.com\/?p=1191"},"modified":"2024-12-12T15:23:14","modified_gmt":"2024-12-12T14:23:14","slug":"denunciar-contenido-facebook","status":"publish","type":"post","link":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/","title":{"rendered":"\u00bfC\u00f3mo denunciar contenido en Facebook?"},"content":{"rendered":"\n<p>Si afirm\u00e1semos que hoy por hoy no somos capaces de pasar un solo d\u00eda sin echar un vistazo a nuestras redes sociales, probablemente no estar\u00edamos muy alejados de la realidad. <strong>Su nivel de popularidad no deja de aumentar a medida que van llegando nuevos usuarios<\/strong> a plataformas como Facebook, Instagram o Whatsapp, entre otras.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>En Facebook, <strong>los contenidos son observados por una IA y por un grupo de moderadores<\/strong> que tratan de controlar su contenido de forma que los usuarios tengan la mayor libertad de expresi\u00f3n posible. Existen una serie de excepciones sobre las que la plataforma es totalmente inflexible, como son: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No se permiten contenidos que pongan en <strong>peligro la integridad f\u00edsica o financiera de las personas.<\/strong><\/li>\n\n\n\n<li>Contenidos que <strong>intimiden a las personas<\/strong> a trav\u00e9s de lenguajes ofensivos.<\/li>\n\n\n\n<li>Contenidos que tengan como objetivo <strong>obtener alg\u00fan beneficio a trav\u00e9s del enga\u00f1o<\/strong> de las personas que utilizan la red social.<\/li>\n<\/ul>\n\n\n\n<p>Pero esto a veces no es suficiente.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo denunciar contenido en Facebook?<\/strong><\/h2>\n\n\n\n<p>Al igual que puedes <strong><a href=\"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-instagram\/\" target=\"_blank\" rel=\"noreferrer noopener\">denunciar contenido en Instagram<\/a><\/strong>, esta otra red social de Mark Zuckerberg tambi\u00e9n te permite <strong>denunciar contenido que consideres ofensivo, racista o que atenta contra la intimidad, la dignidad y el <a href=\"https:\/\/www.repscan.com\/es\/blog\/derecho-al-honor\/\" target=\"_blank\" rel=\"noreferrer noopener\">derecho al honor<\/a><\/strong>, propio o de otras personas. Cuando nos encontremos este tipo de situaciones, <strong>lo mejor que podemos hacer es denunciarlas.<\/strong> No deseemos para nadie lo que no desear\u00edamos para nosotros. Pensemos que es un bien que nos hacemos a nosotros mismos y que ayuda a mantener el bienestar del resto de la comunidad de usuarios de la red social.<\/p>\n\n\n\n<p>Algo que Facebook permite hacer y es una de las primeras cosas que te aconsejamos que hagas &#8211; sobre todo si est\u00e1s recibiendo contenido de car\u00e1cter hom\u00f3fobo, racista, que incite al odio, etc. -, es <strong><a href=\"https:\/\/www.repscan.com\/es\/blog\/eliminar-amigos-facebook\/\" target=\"_blank\" rel=\"noreferrer noopener\">eliminar ese amigo de Facebook<\/a><\/strong> que est\u00e1 publicando ese tipo de im\u00e1genes, v\u00eddeos, &#8230; y que pueden estar da\u00f1\u00e1ndote a ti o a otras personas. Una vez hecho esto, Facebook nos ofrece<strong> diferentes formas de proceder si queremos denunciar, seg\u00fan el tipo de contenido<\/strong>.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Para denunciar una publicaci\u00f3n tienes que hacer lo siguiente:<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ver la publicaci\u00f3n que consideres inapropiada.<\/li>\n\n\n\n<li>Ve a los <strong>tres puntos que est\u00e1n arriba a la derecha de la publicaci\u00f3n.<\/strong><\/li>\n\n\n\n<li>Aparecer\u00e1 un desplegable de opciones donde una de ellas ser\u00e1 <strong>Obtener ayuda o denunciar publicaci\u00f3n.<\/strong><\/li>\n\n\n\n<li>Aqu\u00ed deber\u00e1s <strong>indicar el motivo de la denuncia,<\/strong> ya sea Spam, Incitaci\u00f3n al odio, etc.<\/li>\n<\/ol>\n\n\n\n<p>Dependiendo de aquello que te motive a presentar la denuncia, <strong>Facebook te plantear\u00e1 una serie de opciones m\u00e1s espec\u00edficas.<\/strong> Por ejemplo: Si se trata de una denuncia relacionada con la <em>Incitaci\u00f3n al odio<\/em>, seguidamente podr\u00e1s escoger la raza o etnia, la nacionalidad, etc. Una vez especifiques estos detalles, le das a <strong>Siguiente <\/strong>y sigues los pasos.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Para denunciar un perfil de Facebook haz lo siguiente:<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ve al perfil que crees que es inapropiado o fue usurpado.<\/li>\n\n\n\n<li>Ve a los<strong> tres puntos que est\u00e1n debajo del nombre y a la derecha.<\/strong><\/li>\n\n\n\n<li>Aparecer\u00e1 un desplegable de opciones y clicas donde pone<em> <\/em><strong>Buscar ayuda o denunciar perfil.<\/strong><\/li>\n\n\n\n<li><strong>Indica el motivo<\/strong> por el que denuncias ese perfil y sigue los pasos.<\/li>\n<\/ol>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Para denunciar una foto o v\u00eddeo en Facebook haz lo siguiente:<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Haz clic en el v\u00eddeo o foto<\/strong> para ampliarlo.<\/li>\n\n\n\n<li>Clica en los tres puntos y despu\u00e9s en <strong>Denunciar v\u00eddeo.<\/strong><\/li>\n\n\n\n<li><strong>Indica el motivo<\/strong> de la denuncia y sigue los pasos.<\/li>\n<\/ol>\n\n\n\n<p>No debemos confundir el tipo de contenido que <strong>es aconsejable denunciar <\/strong>con contenido que por preferencias personales no nos guste o interese, ya que este \u00faltimo puede no estar infringiendo las <strong>normas comunitarias propias de Facebook<\/strong>. Denunciar contenido en Facebook es un proceso muy sencillo y que est\u00e1 a nuestro alcance si consideramos que la situaci\u00f3n lo requiere. Si tienes cualquier duda, no dudes en dejarnos tu comentario y te contestaremos lo antes posible.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3317\" class=\"elementor elementor-3317\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-c26d2b3 elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"c26d2b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc9a6b8\" data-id=\"bc9a6b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-635edc3 elementor-widget elementor-widget-spacer\" data-id=\"635edc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b75782d elementor-widget elementor-widget-heading\" data-id=\"b75782d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-small\">\u00bfTienes contenido negativo afectando tu reputaci\u00f3n online?<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc9cd1 elementor-widget elementor-widget-text-editor\" data-id=\"5dc9cd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" data-start=\"203\" data-end=\"319\">Fotos, v\u00eddeos, rese\u00f1as negativas o noticias falsas pueden da\u00f1ar tu imagen. <strong>Te ayudamos a eliminarlos o desindexarlos.<\/strong> <strong data-start=\"271\" data-end=\"317\">D\u00e9janos tus datos y te contactamos.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8efc46c elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"8efc46c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe aria-label='ESP_ZOHO_FORM_BLOG' frameborder=\"0\" style=\"height:1100px;width:99%;border:none;\" src='https:\/\/forms.zohopublic.eu\/repscan\/form\/ESPZOHOFORMBLOG\/formperma\/fNklprMD581Qphnz_99HoDaem83UEE5xWdMM0Kk9Hmk'><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-779c95e elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"779c95e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-346e4c9\" data-id=\"346e4c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f38e866 elementor-widget elementor-widget-heading\" data-id=\"f38e866\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-small\">\u00bfTienes contenido negativo afectando tu reputaci\u00f3n online?<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dc1214 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2dc1214\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03d0b84 elementor-widget elementor-widget-text-editor\" data-id=\"03d0b84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" data-start=\"203\" data-end=\"319\">Fotos, v\u00eddeos, rese\u00f1as negativas o noticias falsas pueden da\u00f1ar tu imagen. <strong>Te ayudamos a eliminarlos o desindexarlos.<\/strong> <strong data-start=\"271\" data-end=\"317\">D\u00e9janos tus datos y te contactamos.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c80e7b elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"9c80e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe aria-label='ESP_ZOHO_FORM_BLOG' frameborder=\"0\" style=\"height:1205px;width:99%;border:none;\" src='https:\/\/forms.zohopublic.eu\/repscan\/form\/ESPZOHOFORMBLOG\/formperma\/fNklprMD581Qphnz_99HoDaem83UEE5xWdMM0Kk9Hmk'><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":22,"featured_media":3128,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[22,68],"tags":[136,128,135,131],"class_list":["post-1191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eliminacion-contenido","category-herramientas-recursos","tag-acciones-reputacionales","tag-privacidad","tag-propiedad-intelectual","tag-seguridad","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo denunciar contenido en Facebook? | RepScan<\/title>\n<meta name=\"description\" content=\"Aprende c\u00f3mo denunciar contenido en Facebook de manera efectiva para proteger tu seguridad y privacidad online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo denunciar contenido en Facebook? | RepScan\" \/>\n<meta property=\"og:description\" content=\"Aprende c\u00f3mo denunciar contenido en Facebook de manera efectiva para proteger tu seguridad y privacidad online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/\" \/>\n<meta property=\"og:site_name\" content=\"RepScan\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-11T18:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-12T14:23:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/10\/denunciar-contenido-facebook.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Repscan News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Repscan News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/\"},\"author\":{\"name\":\"Repscan News\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#\\\/schema\\\/person\\\/c4d43f6c1b0c678c344718d767d178b6\"},\"headline\":\"\u00bfC\u00f3mo denunciar contenido en Facebook?\",\"datePublished\":\"2021-08-11T18:15:00+00:00\",\"dateModified\":\"2024-12-12T14:23:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/\"},\"wordCount\":668,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/denunciar-contenido-facebook.jpg\",\"keywords\":[\"Acciones reputacionales\",\"Privacidad\",\"Propiedad intelectual\",\"Seguridad\"],\"articleSection\":[\"Eliminaci\u00f3n contenido\",\"Herramientas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/\",\"name\":\"\u00bfC\u00f3mo denunciar contenido en Facebook? | RepScan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/denunciar-contenido-facebook.jpg\",\"datePublished\":\"2021-08-11T18:15:00+00:00\",\"dateModified\":\"2024-12-12T14:23:14+00:00\",\"description\":\"Aprende c\u00f3mo denunciar contenido en Facebook de manera efectiva para proteger tu seguridad y privacidad online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/denunciar-contenido-facebook.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/denunciar-contenido-facebook.jpg\",\"width\":1000,\"height\":667,\"caption\":\"denunciar contenido facebook\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/denunciar-contenido-facebook\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo denunciar contenido en Facebook?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/\",\"name\":\"RepScan\",\"description\":\"Plataforma de Reputaci\u00f3n Digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#organization\",\"name\":\"RepScan\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/repscan_header_HQ.png\",\"contentUrl\":\"https:\\\/\\\/www.repscan.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/repscan_header_HQ.png\",\"width\":550,\"height\":130,\"caption\":\"RepScan\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/#\\\/schema\\\/person\\\/c4d43f6c1b0c678c344718d767d178b6\",\"name\":\"Repscan News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b81dd75fe29d497f9d69b4d693ae3b5dc336ed5e61f609711feb2c94e420366?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b81dd75fe29d497f9d69b4d693ae3b5dc336ed5e61f609711feb2c94e420366?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b81dd75fe29d497f9d69b4d693ae3b5dc336ed5e61f609711feb2c94e420366?s=96&d=mm&r=g\",\"caption\":\"Repscan News\"},\"url\":\"https:\\\/\\\/www.repscan.com\\\/es\\\/blog\\\/author\\\/wordpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo denunciar contenido en Facebook? | RepScan","description":"Aprende c\u00f3mo denunciar contenido en Facebook de manera efectiva para proteger tu seguridad y privacidad online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo denunciar contenido en Facebook? | RepScan","og_description":"Aprende c\u00f3mo denunciar contenido en Facebook de manera efectiva para proteger tu seguridad y privacidad online.","og_url":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/","og_site_name":"RepScan","article_published_time":"2021-08-11T18:15:00+00:00","article_modified_time":"2024-12-12T14:23:14+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/10\/denunciar-contenido-facebook.jpg","type":"image\/jpeg"}],"author":"Repscan News","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Repscan News","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/#article","isPartOf":{"@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/"},"author":{"name":"Repscan News","@id":"https:\/\/www.repscan.com\/es\/#\/schema\/person\/c4d43f6c1b0c678c344718d767d178b6"},"headline":"\u00bfC\u00f3mo denunciar contenido en Facebook?","datePublished":"2021-08-11T18:15:00+00:00","dateModified":"2024-12-12T14:23:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/"},"wordCount":668,"commentCount":1,"publisher":{"@id":"https:\/\/www.repscan.com\/es\/#organization"},"image":{"@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/10\/denunciar-contenido-facebook.jpg","keywords":["Acciones reputacionales","Privacidad","Propiedad intelectual","Seguridad"],"articleSection":["Eliminaci\u00f3n contenido","Herramientas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/","url":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/","name":"\u00bfC\u00f3mo denunciar contenido en Facebook? | RepScan","isPartOf":{"@id":"https:\/\/www.repscan.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/#primaryimage"},"image":{"@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/10\/denunciar-contenido-facebook.jpg","datePublished":"2021-08-11T18:15:00+00:00","dateModified":"2024-12-12T14:23:14+00:00","description":"Aprende c\u00f3mo denunciar contenido en Facebook de manera efectiva para proteger tu seguridad y privacidad online.","breadcrumb":{"@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/#primaryimage","url":"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/10\/denunciar-contenido-facebook.jpg","contentUrl":"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/10\/denunciar-contenido-facebook.jpg","width":1000,"height":667,"caption":"denunciar contenido facebook"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repscan.com\/es\/blog\/denunciar-contenido-facebook\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.repscan.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo denunciar contenido en Facebook?"}]},{"@type":"WebSite","@id":"https:\/\/www.repscan.com\/es\/#website","url":"https:\/\/www.repscan.com\/es\/","name":"RepScan","description":"Plataforma de Reputaci\u00f3n Digital","publisher":{"@id":"https:\/\/www.repscan.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repscan.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repscan.com\/es\/#organization","name":"RepScan","url":"https:\/\/www.repscan.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repscan.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/07\/repscan_header_HQ.png","contentUrl":"https:\/\/www.repscan.com\/wp-content\/uploads\/2020\/07\/repscan_header_HQ.png","width":550,"height":130,"caption":"RepScan"},"image":{"@id":"https:\/\/www.repscan.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repscan.com\/es\/#\/schema\/person\/c4d43f6c1b0c678c344718d767d178b6","name":"Repscan News","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8b81dd75fe29d497f9d69b4d693ae3b5dc336ed5e61f609711feb2c94e420366?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b81dd75fe29d497f9d69b4d693ae3b5dc336ed5e61f609711feb2c94e420366?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b81dd75fe29d497f9d69b4d693ae3b5dc336ed5e61f609711feb2c94e420366?s=96&d=mm&r=g","caption":"Repscan News"},"url":"https:\/\/www.repscan.com\/es\/blog\/author\/wordpress\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/posts\/1191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/comments?post=1191"}],"version-history":[{"count":0,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/posts\/1191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/media\/3128"}],"wp:attachment":[{"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/media?parent=1191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/categories?post=1191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repscan.com\/es\/wp-json\/wp\/v2\/tags?post=1191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}